{"id":13841,"date":"2024-05-27T01:22:24","date_gmt":"2024-05-27T04:22:24","guid":{"rendered":"https:\/\/vidasraras.org.br\/sitewp\/?p=13841"},"modified":"2024-05-27T01:22:26","modified_gmt":"2024-05-27T04:22:26","slug":"a-monique-cristina-e-um-exemplo-de-mulher","status":"publish","type":"post","link":"https:\/\/vidasraras.org.br\/sitewp\/a-monique-cristina-e-um-exemplo-de-mulher\/","title":{"rendered":"A Monique Cristina \u00e9 um Exemplo de Mulher"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Meu nome \u00e9 Monique Cristina, tenho 23 anos.<br>Tenho Epidermolise Bolhosa uma doen\u00e7a rara gen\u00e9tica de pele que torna a pele sens\u00edvel, como a asa de uma borboleta, gerando algumas les\u00f5es e poss\u00edveis atrofias al\u00e9m de necess\u00e1rio de m\u00faltiplos cuidados m\u00e9dicos.<br><br>Eu sou escritora, palestrante motivacional, participante de um projeto de Gen\u00e9tica da faculdade Albert Einstein ( Geneall Ci\u00eancia) e embaixadora Urgo cuidando das borboletas para mostrar que pessoas como eu n\u00e3o sou incapazes de viver, mesmo tendo uma doen\u00e7a rara ainda sou uma pessoa com sonhos e direito de viver.<br>Segue o link de um v\u00eddeo contando minha hist\u00f3ria de vida: https:\/\/youtu.be\/wvxte_7diYE<br><br>Escrevi meu primeiro livro com 13 anos, ele conta a hist\u00f3ria de uma menina que descobri que \u00e9 princesa do mundo m\u00e1gico e como ela lida com isso. Um livro com base no meu mundo de imagina\u00e7\u00e3o que eu quis escrever para mostrar que existe uma pessoa &#8220;al\u00e9m da doen\u00e7a rara&#8221;. Depois aos 14 dei minha primeira palestra para divulga\u00e7\u00e3o da minha vida, minha maneira de ver o mundo, meu livro e a minha doen\u00e7a e nunca mais parei este trabalho.<br><br>Descobri um amor em compartilhar minha experiencias de vida e receber experiencias em troca. Pretendo ter forma\u00e7oes academicas que melhorem meu trabalho e que assim eu possa ajudar a melhorar a vida de uma pessoa que assim como eu tem sonhos dos mais simples como se formar, dirigir, trabalhar at\u00e9 os maiores sonhos como lan\u00e7ar um livro, viajar o mundo, ser uma comunicadora, ser ouvido e respeitado por ser quem \u00e9.<br><br>Participo de eventos, palestras, entrevistas para divulgacao do meu trabalho e da minha viv\u00eancia.<br>Estive no programa da F\u00e1tima Bernardes segui o link: http:\/\/globoplay.globo.com\/v\/8010360\/<br><br>Meu principal objetivo \u00e9 mostrar que pessoas com EB, doen\u00e7as raras, defici\u00eancias, pessoas como eu que sofrem por fazer parte de uma minoria e lutam para ser ouvidos e terem seus direitos de viver s\u00e3o capazes de tudo principalmente quando unidos.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-medium is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/vidasraras.org.br\/sitewp\/wp-content\/uploads\/2024\/05\/Screenshot-2024-05-26-211003-240x300.png\" alt=\"\" class=\"wp-image-13842\" width=\"482\" height=\"603\" srcset=\"https:\/\/vidasraras.org.br\/sitewp\/wp-content\/uploads\/2024\/05\/Screenshot-2024-05-26-211003-240x300.png 240w, https:\/\/vidasraras.org.br\/sitewp\/wp-content\/uploads\/2024\/05\/Screenshot-2024-05-26-211003-819x1024.png 819w, https:\/\/vidasraras.org.br\/sitewp\/wp-content\/uploads\/2024\/05\/Screenshot-2024-05-26-211003-768x960.png 768w, https:\/\/vidasraras.org.br\/sitewp\/wp-content\/uploads\/2024\/05\/Screenshot-2024-05-26-211003.png 934w\" sizes=\"(max-width: 482px) 100vw, 482px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Meu Instagram <a href=\"https:\/\/www.instagram.com\/moniquecristinaoficial\/\">https:\/\/www.instagram.com\/moniquecristinaoficial\/<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Links de participa\u00e7\u00f5es art\u00edsticas,sociais de Monique Cristina;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Start novos come\u00e7os, palco aberto e pe\u00e7a de teatro:<br><a href=\"https:\/\/www.instagram.com\/p\/CWVvqLvLp79\/?igshid=YmMyMTA2M2Y=\">https:\/\/www.instagram.com\/p\/CWVvqLvLp79\/?igshid=YmMyMTA2M2Y=<\/a><br><a href=\"https:\/\/www.instagram.com\/p\/CWnS-Glr1Vw\/?igshid=YmMyMTA2M2Y=\">https:\/\/www.instagram.com\/p\/CWnS-Glr1Vw\/?igshid=YmMyMTA2M2Y=<\/a><\/li><li>leitura de poemas em um sarau :<br><a href=\"https:\/\/www.instagram.com\/reel\/CZUaHqqJ4sb\/?igshid=YmMyMTA2M2Y=\">https:\/\/www.instagram.com\/reel\/CZUaHqqJ4sb\/?igshid=YmMyMTA2M2Y=<\/a><\/li><li>evento na c\u00e2mara dos vereadores em Taubat\u00e9 sobre dia dos raros:<br><a href=\"https:\/\/www.camarataubate.sp.gov.br\/paginas\/portal\/noticia?id=2488\">https:\/\/www.camarataubate.sp.gov.br\/paginas\/portal\/noticia?id=2488<\/a><\/li><li>divulga\u00e7\u00e3o sobre os cuidados com sa\u00fade da mulher pela prefeitura de Taubat\u00e9;<br><a href=\"https:\/\/www.instagram.com\/tv\/CbCxGp9tKM3\/?igshid=YmMyMTA2M2Y=\">https:\/\/www.instagram.com\/tv\/CbCxGp9tKM3\/?igshid=YmMyMTA2M2Y=<\/a><\/li><li>V\u00eddeo promocional Urgo cuidando das borboletas:<br><a href=\"https:\/\/youtu.be\/kRzNK3JXZOs\">https:\/\/youtu.be\/kRzNK3JXZOs<\/a><\/li><li>Cartilha sobre Epidermolise Bolhosa:<br><a href=\"https:\/\/drive.google.com\/file\/d\/1VWIPy5Exen-xe9JhSPmZ7a5FQ4LoNIsg\/view\">https:\/\/drive.google.com\/file\/d\/1VWIPy5Exen-xe9JhSPmZ7a5FQ4LoNIsg\/view<\/a><\/li><li>entrevistas:<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.portalr3.com.br\/2015\/08\/espaco-cultural-da-camara-de-taubate-sedia-noite-de-autografo-de-jovem-escritora\/\">https:\/\/www.portalr3.com.br\/2015\/08\/espaco-cultural-da-camara-de-taubate-sedia-noite-de-autografo-de-jovem-escritora\/<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/carlotas.org\/BR\/jornal\/106-jornal\/contos\/979-a-monique-e-a-menina-borboleta-e-chegou-em-carlotas-com-um-dialogo-importante\">https:\/\/carlotas.org\/BR\/jornal\/106-jornal\/contos\/979-a-monique-e-a-menina-borboleta-e-chegou-em-carlotas-com-um-dialogo-importante<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.7segundos.com.br\/arapiraca\/noticias\/2020\/01\/08\/138821-palestra-beneficente-vai-ajudar-criancas-borboletas\">https:\/\/www.7segundos.com.br\/arapiraca\/noticias\/2020\/01\/08\/138821-palestra-beneficente-vai-ajudar-criancas-borboletas<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/m.facebook.com\/story.php?story_fbid=pfbid031h5w4tSKHgW57vU7Pz6yNMsFGtrfDYZPqVGPoFpYgha9LDwsd64Vd3zFg1Sxj3pNl&amp;id=100003689077077&amp;sfnsn=wiwspwa\">https:\/\/m.facebook.com\/story.php?story_fbid=pfbid031h5w4tSKHgW57vU7Pz6yNMsFGtrfDYZPqVGPoFpYgha9LDwsd64Vd3zFg1Sxj3pNl&amp;id=100003689077077&amp;sfnsn=wiwspwa<\/a><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-faculdade-dehoniana wp-block-embed-faculdade-dehoniana\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"ENpFd49ZBt\"><a href=\"https:\/\/dehoniana.edu.br\/aluna-se-torna-academica-da-academia-valeparaibana-de-letras-e-artes\/\">Aluna se torna acad\u00eamica da Acad\u00eamia Valepara\u00edbana de Letras e Artes<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;Aluna se torna acad\u00eamica da Acad\u00eamia Valepara\u00edbana de Letras e Artes&#8221; &#8212; Faculdade Dehoniana\" src=\"https:\/\/dehoniana.edu.br\/aluna-se-torna-academica-da-academia-valeparaibana-de-letras-e-artes\/embed\/#?secret=lyZlaS6n3O#?secret=ENpFd49ZBt\" data-secret=\"ENpFd49ZBt\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"CONHE\u00c7A A A EPIDERM\u00d3LISE BOLHOSA QUE \u00c9 UMA DOEN\u00c7A GEN\u00c9TICA E HEREDIT\u00c1RIA RARA\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/_JhsW5AAcrw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www1.folha.uol.com.br\/equilibrioesaude\/2023\/10\/programa-de-analise-de-genes-de-doencas-raras-esbarra-em-falta-de-verba-e-estrutura.shtml\">https:\/\/www1.folha.uol.com.br\/equilibrioesaude\/2023\/10\/programa-de-analise-de-genes-de-doencas-raras-esbarra-em-falta-de-verba-e-estrutura.shtml<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estes s\u00e3o alguns links sobre minha trajet\u00f3ria e sobre o que desejo passar com a escrita, comunica\u00e7\u00e3o e as artes sendo uma pessoa com defici\u00eancia f\u00edsica e doen\u00e7a rara quero levar a arte e a sociedade em geral a voz das pessoas que s\u00e3o minorias .<br>Grata pela aten\u00e7\u00e3o,<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Meu nome \u00e9 Monique Cristina, tenho 23 anos.Tenho Epidermolise Bolhosa&hellip;<\/p>\n<p> <a class=\"more-link\" href=\"https:\/\/vidasraras.org.br\/sitewp\/a-monique-cristina-e-um-exemplo-de-mulher\/\">Leia mais<\/a><\/p>\n","protected":false},"author":6,"featured_media":13842,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[256,3],"tags":[],"class_list":["post-13841","post","type-post","status-publish","format-standard","has-post-thumbnail","category-conte-sua-historia","category-noticias"],"_links":{"self":[{"href":"https:\/\/vidasraras.org.br\/sitewp\/wp-json\/wp\/v2\/posts\/13841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vidasraras.org.br\/sitewp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vidasraras.org.br\/sitewp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vidasraras.org.br\/sitewp\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/vidasraras.org.br\/sitewp\/wp-json\/wp\/v2\/comments?post=13841"}],"version-history":[{"count":2,"href":"https:\/\/vidasraras.org.br\/sitewp\/wp-json\/wp\/v2\/posts\/13841\/revisions"}],"predecessor-version":[{"id":13844,"href":"https:\/\/vidasraras.org.br\/sitewp\/wp-json\/wp\/v2\/posts\/13841\/revisions\/13844"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vidasraras.org.br\/sitewp\/wp-json\/wp\/v2\/media\/13842"}],"wp:attachment":[{"href":"https:\/\/vidasraras.org.br\/sitewp\/wp-json\/wp\/v2\/media?parent=13841"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vidasraras.org.br\/sitewp\/wp-json\/wp\/v2\/categories?post=13841"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vidasraras.org.br\/sitewp\/wp-json\/wp\/v2\/tags?post=13841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}